{"id":908,"date":"2018-10-17T13:33:47","date_gmt":"2018-10-17T13:33:47","guid":{"rendered":"https:\/\/hightechextracts.com\/?p=357"},"modified":"2023-03-20T20:18:43","modified_gmt":"2023-03-20T20:18:43","slug":"nuestras-bombas-estan-dimensionadas-para-un-produccion-optima","status":"publish","type":"post","link":"https:\/\/hightechextracts.com\/es\/nuestras-bombas-estan-dimensionadas-para-un-produccion-optima\/","title":{"rendered":"Nuestras bombas est\u00e1n dimensionadas para un producci\u00f3n \u00f3ptima"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"908\" class=\"elementor elementor-908\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-386614d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"386614d9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-423e5bc0\" data-id=\"423e5bc0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41a0a188 elementor-widget elementor-widget-text-editor\" data-id=\"41a0a188\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>El dimensionamiento perfecto se realiz\u00f3 despu\u00e9s del an\u00e1lisis de un mill\u00f3n de etiquetas de datos de procesos dormitados y la evaluaci\u00f3n de la eficiencia.\u00a0Puede ver los resultados de nuestros esfuerzos en este gr\u00e1fico de superficie.<\/p><p>\u00a0<\/p><p>En nuestros sistemas hemos encontrado la mejor combinaci\u00f3n de\u00a0<strong>presi\u00f3n de proceso, relaci\u00f3n\u00a0de flujo de CO2\/volumen del extractor<\/strong>\u00a0y\u00a0<strong>eficiencia<\/strong> del proceso.\u00a0As\u00ed que para cada volumen de extractor utilizamos la bomba m\u00e1s eficiente, teniendo en cuenta una presi\u00f3n de proceso \u00f3ptima.\u00a0De hecho, para nuestros vol\u00famenes, los mejores flujos de bomba de CO2 son:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0b23fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0b23fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81d8449\" data-id=\"81d8449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26761bb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"26761bb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/hightechextracts.com\/es\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bid\u00f3n de 5 L = 25 kg\/h de flujo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bid\u00f3n de 10 L = 50 kg\/h de flujo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bid\u00f3n de 20 L = 100 kg\/h de flujo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bid\u00f3n de 100 L = 500 kg\/h de flujo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bid\u00f3n de 200 L = 1000 kg\/h de flujo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bid\u00f3n de 500 L = 2500 kg\/h de flujo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38d9b40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38d9b40\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8cb20bf\" data-id=\"8cb20bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-292c459 elementor-widget elementor-widget-text-editor\" data-id=\"292c459\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Aunque la\u00a0<strong>relaci\u00f3n flujo CO2\/volumen extractor<\/strong> no es un par\u00e1metro cient\u00edfico para evaluar la cin\u00e9tica de extracci\u00f3n de compuestos qu\u00edmicos (utilizamos kg CO2\/kg materia prima o, para compuestos espec\u00edficos, su solubilidad real por kg CO2 fluido), se considera suficientemente bueno para el dimensionamiento inicial.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pump Flow: The perfect sizing was done after the analysis of a million dozed processes data tag and efficiency evaluation. You can see the result of our efforts in this surface plot. In our systems we found the best combination between\u00a0Process Pressure,\u00a0CO2\u00a0Flow \/ Extractor Volume ratio and\u00a0Efficiency\u00a0of the process.<\/p>\n","protected":false},"author":1,"featured_media":3610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"categories":[6],"tags":[18],"_links":{"self":[{"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/posts\/908"}],"collection":[{"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/comments?post=908"}],"version-history":[{"count":7,"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/posts\/908\/revisions"}],"predecessor-version":[{"id":7179,"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/posts\/908\/revisions\/7179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/media\/3610"}],"wp:attachment":[{"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/media?parent=908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/categories?post=908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hightechextracts.com\/es\/wp-json\/wp\/v2\/tags?post=908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}